{"id":125031,"date":"2026-05-07T05:00:20","date_gmt":"2026-05-07T11:00:20","guid":{"rendered":"https:\/\/uswps06.newsmemory.com\/northernplainsindependent\/news\/2026\/05\/07\/move-unwanted-person-five-domestic\/?destination=northern-plains-independent"},"modified":"2026-05-07T05:02:16","modified_gmt":"2028-10-23T05:02:16","slug":"move-unwanted-person-five-domestic","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2026\/05\/07\/move-unwanted-person-five-domestic\/?destination=northern-plains-independent","title":{"rendered":"move unwanted person, five; domestic &#8230;."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>move unwanted person, five; domestic abuse, one; domestic\/  elder abuse, one; domestic\/  family disturbance, three; follow up, two; harassment,  two; harassment\/ electronic, one; loitering\/ panhandling, three; medical assistance, four; misdial 911, two; missing person\/adult, one; other, one; public intoxication\/  open container, two; runaway\/female, one; stolen property, one; theft, one; tra  crime\/careless<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/125031"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=125031"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/125031\/revisions"}],"predecessor-version":[{"id":125068,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/125031\/revisions\/125068"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=125031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=125031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=125031"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=125031"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=125031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}