{"id":125028,"date":"2026-05-07T05:01:30","date_gmt":"2026-05-07T11:01:30","guid":{"rendered":"https:\/\/uswps06.newsmemory.com\/northernplainsindependent\/news\/2026\/05\/07\/miss-frazer\/?destination=northern-plains-independent"},"modified":"2026-05-07T05:06:06","modified_gmt":"2028-10-23T05:06:06","slug":"miss-frazer","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2026\/05\/07\/miss-frazer\/?destination=northern-plains-independent","title":{"rendered":"Miss Frazer"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Kyrsten Miller will represent  Frazer at the Miss Montana competition May 30 at Butte\u2019s Mother Lode Theatre. \u201cMy ultimate goal is just representation in general, since we don\u2019t have any around here,\u201d Miller told the  Northern  Plains Independent.<br \/>\n\t\u201cI want to open the door for other young women to compete. It\u2019s a great opportunity to gain confi dence, a sisterhood and scholarships. It\u2019s<\/p>\n","protected":false},"author":1,"featured_media":125013,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/125028"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=125028"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/125028\/revisions"}],"predecessor-version":[{"id":125089,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/125028\/revisions\/125089"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media\/125013"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=125028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=125028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=125028"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=125028"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=125028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}