{"id":121858,"date":"2026-03-19T05:03:20","date_gmt":"2026-03-19T11:03:20","guid":{"rendered":"https:\/\/uswps06.newsmemory.com\/northernplainsindependent\/news\/2026\/03\/19\/poplar-fire-department\/?destination=northern-plains-independent"},"modified":"2026-03-19T05:10:35","modified_gmt":"2028-09-04T05:10:35","slug":"poplar-fire-department","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2026\/03\/19\/poplar-fire-department\/?destination=northern-plains-independent","title":{"rendered":"Poplar Fire Department"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Members and supporters of the Poplar Volunteer Fire Department lined both sides of U.S. Highway 2 near Fort Peck Community College on March 11 as part of annual  fundraising efforts. To contribute, call 406-768-3313 or write to poplarfiredept@gmail.com.  (Photo by James Walling)<\/p>\n","protected":false},"author":1,"featured_media":121851,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/121858"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=121858"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/121858\/revisions"}],"predecessor-version":[{"id":122043,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/121858\/revisions\/122043"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media\/121851"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=121858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=121858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=121858"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=121858"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=121858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}