{"id":121510,"date":"2026-03-12T05:00:30","date_gmt":"2026-03-12T11:00:30","guid":{"rendered":"https:\/\/uswps06.newsmemory.com\/northernplainsindependent\/news\/2026\/03\/12\/snowpack-deficits-continue-to-grow-across-state\/?destination=northern-plains-independent"},"modified":"2026-03-12T05:01:47","modified_gmt":"2028-08-28T05:01:47","slug":"snowpack-deficits-continue-to-grow-across-state","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2026\/03\/12\/snowpack-deficits-continue-to-grow-across-state\/?destination=northern-plains-independent","title":{"rendered":"Snowpack Deficits Continue  To Grow Across State"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>As of March 1, most Montana  basins are now reporting  below normal snowpack, ranging from around 60 percent  to 95 percent of median.<br \/>\n\t  \u201cThe current snowpack percentages compare the amount of snow water equivalent  in the mountains to the median amount typically  seen on March 1. During March and April, these values  generally remain more stable than people might expect. For example, during a<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/121510"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=121510"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/121510\/revisions"}],"predecessor-version":[{"id":121583,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/121510\/revisions\/121583"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=121510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=121510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=121510"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=121510"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=121510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}