{"id":121398,"date":"2026-03-12T05:01:30","date_gmt":"2026-03-12T11:01:30","guid":{"rendered":"https:\/\/uswps06.newsmemory.com\/northernplainsindependent\/news\/2026\/03\/12\/psc-approves-interim-rates-for-mdu\/?destination=northern-plains-independent"},"modified":"2026-03-12T05:05:16","modified_gmt":"2028-08-28T05:05:16","slug":"psc-approves-interim-rates-for-mdu","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2026\/03\/12\/psc-approves-interim-rates-for-mdu\/?destination=northern-plains-independent","title":{"rendered":"PSC Approves Interim Rates For MDU"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>During a work session on Tuesday, March 3, the Montana  Public Service Commission  approved, after careful review, a request by Montana- Dakota Utilities (MDU) for an interim electric rate increase  in Docket 2025.09.072.<br \/>\n\t  In its full rate case submitted  last September, MDU requested commission approval  of an annual revenue increase of $14.1 million to cover the company\u2019s additional  costs of<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"news-destination":[13],"news-source":[12],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/121398"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=121398"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/121398\/revisions"}],"predecessor-version":[{"id":121603,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/121398\/revisions\/121603"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=121398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=121398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=121398"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=121398"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=121398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}