{"id":112211,"date":"2025-10-02T05:04:30","date_gmt":"2025-10-02T11:04:30","guid":{"rendered":"https:\/\/uswps06.newsmemory.com\/northernplainsindependent\/news\/2025\/10\/02\/man-faces-sexual-attempted-sexual-assault-charge\/?destination=northern-plains-independent"},"modified":"2025-10-02T05:13:48","modified_gmt":"2028-03-20T05:13:48","slug":"man-faces-sexual-attempted-sexual-assault-charge","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2025\/10\/02\/man-faces-sexual-attempted-sexual-assault-charge\/?destination=northern-plains-independent","title":{"rendered":"Man Faces Sexual Attempted Sexual Assault Charge"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Patrick Follet, 24, originally of Frazer, is facing the charge of attempted sexual assault in Yellowstone County.<br \/>\n\t  Follet is accused of following  teenagers at a football  game at Daylis Stadium in Billings on Friday, Sept. 19, and attempting to grope them.<br \/>\n\t Bond was set at $35,000 during a hearing last week.<br \/>\n\t  His next court appearance  is scheduled for Jan. 6, 2026.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/112211"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=112211"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/112211\/revisions"}],"predecessor-version":[{"id":112394,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/112211\/revisions\/112394"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=112211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=112211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=112211"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=112211"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=112211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}