{"id":111447,"date":"2025-09-18T05:03:00","date_gmt":"2025-09-18T11:03:00","guid":{"rendered":"https:\/\/uswps06.newsmemory.com\/northernplainsindependent\/news\/2025\/09\/18\/poplar-drops-game-in-culbertson\/?destination=northern-plains-independent"},"modified":"2025-09-18T05:11:09","modified_gmt":"2028-03-06T05:11:09","slug":"poplar-drops-game-in-culbertson","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2025\/09\/18\/poplar-drops-game-in-culbertson\/?destination=northern-plains-independent","title":{"rendered":"Poplar Drops Game In Culbertson"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>The Culbertson Cowboys jumped out to a 38-0 halftime  lead and defeated Poplar,  58-8, at home on Friday, Sept. 12.<br \/>\n\t  The Cowboys struck on their first offensive possession  when quarterback Brooks Solem broke loose for a 38-yard touchdown run for a 6-0 lead.<br \/>\n\t  After a sack by Micah Eagle  Boy put the Indians back to the one-yard line, Aden Drake sacked Poplar\u2019s quarterback  for a safety.<\/p>\n","protected":false},"author":1,"featured_media":111438,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/111447"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=111447"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/111447\/revisions"}],"predecessor-version":[{"id":111604,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/111447\/revisions\/111604"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media\/111438"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=111447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=111447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=111447"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=111447"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=111447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}