{"id":110628,"date":"2025-09-04T05:02:50","date_gmt":"2025-09-04T11:02:50","guid":{"rendered":"https:\/\/uswps06.newsmemory.com\/northernplainsindependent\/news\/2025\/09\/04\/warriors-drop-first-football-game-of-season\/?destination=northern-plains-independent"},"modified":"2025-09-04T05:08:50","modified_gmt":"2028-02-21T05:08:50","slug":"warriors-drop-first-football-game-of-season","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2025\/09\/04\/warriors-drop-first-football-game-of-season\/?destination=northern-plains-independent","title":{"rendered":"Warriors Drop First Football Game Of Season"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Froid\/Lake and Brockton started their football seasons with a six-man battle in Medicine  Lake on Saturday, Aug. 30. The Red Hawks emerged with a 54-13 conference victory.<br \/>\n\t  The Red Hawks accounted for the game\u2019s first big play when Owen Logan recovered a fumble at the Brockton 19. Froid\/Lake reached the end zone on a nine-yard pass from Rylan Young to Cody Olson.<br \/>\n\t  The Warriors responded  by<\/p>\n","protected":false},"author":1,"featured_media":110748,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/110628"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=110628"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/110628\/revisions"}],"predecessor-version":[{"id":110758,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/110628\/revisions\/110758"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media\/110748"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=110628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=110628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=110628"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=110628"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=110628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}