{"id":107602,"date":"2025-07-17T05:05:30","date_gmt":"2025-07-17T11:05:30","guid":{"rendered":"https:\/\/uswps06.newsmemory.com\/northernplainsindependent\/news\/2025\/07\/17\/commissioners-approve-contract-extensions\/?destination=northern-plains-independent"},"modified":"2025-07-17T05:16:27","modified_gmt":"2028-01-03T05:16:27","slug":"commissioners-approve-contract-extensions","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2025\/07\/17\/commissioners-approve-contract-extensions\/?destination=northern-plains-independent","title":{"rendered":"Commissioners  Approve Contract  Extensions"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>The Roosevelt County Commissioners  approved continuing with their contract with the Healthy is Wellness program during their meeting on Tuesday, July 8.<br \/>\n\t  Being part of the program is voluntarily  for employees. The county and its health provider each pay half of the fees for the program.<br \/>\n\t  Cost for the county is about $1,100 a month.<br \/>\n\t  \u201cIt\u2019s pretty successful,\u201d Commissioner  Gordon Oelkers<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/107602"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=107602"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/107602\/revisions"}],"predecessor-version":[{"id":107868,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/107602\/revisions\/107868"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=107602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=107602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=107602"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=107602"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=107602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}