{"id":107115,"date":"2025-07-10T05:02:30","date_gmt":"2025-07-10T11:02:30","guid":{"rendered":"https:\/\/uswps06.newsmemory.com\/northernplainsindependent\/news\/2025\/07\/10\/commissioners-cover-new-hired-employees\/?destination=northern-plains-independent"},"modified":"2025-07-10T05:09:27","modified_gmt":"2027-12-27T05:09:27","slug":"commissioners-cover-new-hired-employees","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2025\/07\/10\/commissioners-cover-new-hired-employees\/?destination=northern-plains-independent","title":{"rendered":"Commissioners Cover New Hired Employees"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>The Roosevelt County Commissioners  approved a slate of hires during their meeting Tuesday, July 1.<br \/>\n\t  Among the hires were temporary seasonal employees Darrell Synan in the Bainville area, Charles Pribbernow  in the Poplar area and Roger  Chamber in the McCabe area for mowing.<br \/>\n\t  Commissioner Robert Toavs explained  mowing will be conducted earlier than normal to hopefully have less fire danger.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[95],"tags":[],"news-destination":[13],"news-source":[12],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/107115"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=107115"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/107115\/revisions"}],"predecessor-version":[{"id":107412,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/107115\/revisions\/107412"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=107115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=107115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=107115"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=107115"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=107115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}