{"id":106458,"date":"2025-06-26T05:03:40","date_gmt":"2025-06-26T11:03:40","guid":{"rendered":"https:\/\/uswps06.newsmemory.com\/northernplainsindependent\/news\/2025\/06\/26\/garfield-pleads-guilty-to-aggravated-sexual-abuse\/?destination=northern-plains-independent"},"modified":"2025-06-26T05:12:21","modified_gmt":"2027-12-13T05:12:21","slug":"garfield-pleads-guilty-to-aggravated-sexual-abuse","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2025\/06\/26\/garfield-pleads-guilty-to-aggravated-sexual-abuse\/?destination=northern-plains-independent","title":{"rendered":"Garfield Pleads Guilty To Aggravated Sexual Abuse"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>A Poplar man accused of sexual abuse on the Fort Peck Indian Reservation admitted to charges on Tuesday, June 17, U.S. Attorney Kurt Alme said.<br \/>\n\t  The defendant, Chucho Cruzito Garfield, 21, pleaded guilty to aggravated sexual abuse. Garfield faces life imprisonment,  a $250,000 fine and five years to life of supervised release.  Chief U.S. District Judge Brian M. Morris presided and will determine<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/106458"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=106458"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/106458\/revisions"}],"predecessor-version":[{"id":106632,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/106458\/revisions\/106632"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=106458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=106458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=106458"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=106458"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=106458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}