{"id":100286,"date":"2025-03-13T05:02:30","date_gmt":"2025-03-13T11:02:30","guid":{"rendered":"https:\/\/uswps06.newsmemory.com\/northernplainsindependent\/news\/2025\/03\/13\/poplar-wins-tournament-game-against-conrad\/?destination=northern-plains-independent"},"modified":"2025-03-13T05:08:33","modified_gmt":"2027-08-30T05:08:33","slug":"poplar-wins-tournament-game-against-conrad","status":"publish","type":"post","link":"https:\/\/www.northernplainsindependent.com\/2025\/03\/13\/poplar-wins-tournament-game-against-conrad\/?destination=northern-plains-independent","title":{"rendered":"Poplar Wins Tournament Game Against Conrad"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>The Poplar Indians gained the upper-hand in the second  half to defeat Conrad, 5947, in loser-out action at the Northern B divisional boys\u2019 basketball tournament in Cut Bank on Friday, March 7.<br \/>\n\t After trailing by a 23-20 half-time margin, the Indians scored 18 points in the third quarter for a 38-38 deadlock.<br \/>\n\t  The Indians then struck for 21 points in the fourth period for the 12-point victory.<\/p>\n","protected":false},"author":1,"featured_media":100285,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"news-destination":[14],"news-source":[11],"_links":{"self":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/100286"}],"collection":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/comments?post=100286"}],"version-history":[{"count":1,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/100286\/revisions"}],"predecessor-version":[{"id":100413,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/posts\/100286\/revisions\/100413"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media\/100285"}],"wp:attachment":[{"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/media?parent=100286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/categories?post=100286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/tags?post=100286"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-destination?post=100286"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.northernplainsindependent.com\/northernplainsindependent\/news\/wp-json\/wp\/v2\/news-source?post=100286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}